{"id":147,"date":"2025-08-26T09:53:41","date_gmt":"2025-08-26T09:53:41","guid":{"rendered":"https:\/\/blog.chataignon.org\/joseph\/?p=147"},"modified":"2025-08-26T09:53:41","modified_gmt":"2025-08-26T09:53:41","slug":"les-wrappers-et-le-scaffolding-sont-la-meme-chose","status":"publish","type":"post","link":"https:\/\/blog.chataignon.org\/joseph\/fr\/post-147\/les-wrappers-et-le-scaffolding-sont-la-meme-chose\/","title":{"rendered":"Les \u00abwrappers\u00bb et le \u00abscaffolding\u00bb sont la m\u00eame chose"},"content":{"rendered":"\n<p>L\u2019essor des LLM (<em>Large Language Models<\/em>) d\u00e9clench\u00e9 par ChatGPT n&rsquo;a pas seulement profit\u00e9 aux grands laboratoires qui d\u00e9veloppent des mod\u00e8les de fondation. De nombreuses startups ont \u00e9merg\u00e9, exploitant ces mod\u00e8les pour des applications pratiques. Elles sont parfois qualifi\u00e9es de simples \u00ab wrappers ChatGPT \u00bb (<em>\u00ab de l&#8217;emballage autour de ChatGPT \u00bb<\/em>), destin\u00e9es \u00e0 \u00eatre absorb\u00e9es par les grands laboratoires d\u00e8s qu&rsquo;un mod\u00e8le se montrerait rentable. Pourtant, deux ou trois ans plus tard, certains de ces wrappers sont toujours l\u00e0 et se portent m\u00eame tr\u00e8s bien (Perplexity et Cursor par exemple). Alors, les wrappers IA sont-ils l\u00e0 pour durer ?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u00ab C&rsquo;est juste de l&#8217;emballage \u00bb<\/h4>\n\n\n\n<p>Le m\u00e9pris envers ces \u00ab wrappers IA \u00bb repose sur l\u2019hypoth\u00e8se que la seule partie difficile d\u2019une application d\u2019IA est <em>l\u2019IA elle-m\u00eame<\/em>, et que ces wrappers sont donc facilement reproductibles. Les grands laboratoires n\u2019auraient qu\u2019\u00e0 attendre qu\u2019un wrapper devienne populaire, puis le copier et l\u2019int\u00e9grer \u00e0 leurs propres produits.<\/p>\n\n\n\n<p>En plus de leur ma\u00eetrise des mod\u00e8les de fondation, ils auraient un atout ma\u00eetre dans la possibilit\u00e9 de couper l\u2019acc\u00e8s aux mod\u00e8les pour leurs concurrents.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">If Apple buys Perplexity, Cook will not only have demonstrated that he&#39;s a poor product executive, but also that he&#39;s a poor businessman.<br><br>Perplexity is nothing but a cheap wrapper around a poor-quality generic search engine and a language model hyped by people who wouldn&#39;t feel\u2026<\/p>&mdash; BURKOV (@burkov) <a href=\"https:\/\/twitter.com\/burkov\/status\/1938336023190331716?ref_src=twsrc%5Etfw\">June 26, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>En fin de compte, l\u2019id\u00e9e sous-jacente est que les \u00ab wrappers \u00bb apportent peu de valeur au march\u00e9, et sont donc rempla\u00e7ables.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Les wrappers sont toujours l\u00e0<\/h4>\n\n\n\n<p>Malgr\u00e9 les doutes \u00e9mis \u00e0 leur \u00e9gard, ces startups de \u00ab wrappers \u00bb ont continu\u00e9 \u00e0 se d\u00e9velopper et se portent toujours aussi bien aujourd\u2019hui. Elles se r\u00e9partissent principalement en trois cat\u00e9gories : les IDE (applications pour \u00e9crire du code) comme Cursor, Lovable et Replit ; les interfaces de recherche comme Perplexity et you.com ; et les assistants de conception graphique (pour cr\u00e9er des pr\u00e9sentations, des vid\u00e9os, des pages web, etc.).<\/p>\n\n\n\n<p>Comme l\u2019avaient pr\u00e9dit les critiques, les grands laboratoires ont copi\u00e9 (ou tent\u00e9 de copier) les wrappers \u00e0 succ\u00e8s et les ont int\u00e9gr\u00e9s \u00e0 leurs plateformes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Google a lanc\u00e9 Firebase Studio, son IDE aliment\u00e9 par l\u2019IA <\/li>\n\n\n\n<li>Tous les grands labos proposent d\u00e9sormais un mode de recherche web et de recherche approfondie inspir\u00e9 de Perplexity dans leurs interfaces de conversation <\/li>\n\n\n\n<li>Tous ont aussi ajout\u00e9 des fonctionnalit\u00e9s de canevas\/artefacts pour aider \u00e0 la g\u00e9n\u00e9ration d\u2019images et la cr\u00e9ation de pages web <\/li>\n<\/ul>\n\n\n\n<p>Ces tentatives de copie ont connu des succ\u00e8s variables, mais m\u00eame les plus r\u00e9ussies n\u2019ont pas \u00e9limin\u00e9 les wrappers originaux. Ils coexistent simplement, atteignant diff\u00e9rents segments de march\u00e9.<\/p>\n\n\n\n<p>Quant \u00e0 l\u2019atout des grands laboratoires, leur monopole sur les bons mod\u00e8les, il a \u00e9t\u00e9 supprim\u00e9 par la publication de mod\u00e8les open-source performants comme Deepseek et Qwen, ainsi que par l\u2019arriv\u00e9e des fournisseurs d\u2019inf\u00e9rence qui les rendent disponibles \u00e0 bas prix.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo; \u00ab AI Scaffolding \u00bb, la nouvelle tendance<\/h4>\n\n\n\n<p>Lorsque l\u2019engouement initial autour des grands mod\u00e8les de langage a commenc\u00e9 \u00e0 se calmer, de nombreuses entreprises ont r\u00e9alis\u00e9 que les gains de productivit\u00e9 r\u00e9volutionnaires promis ne se mat\u00e9rialisaient pas aussi vite qu\u2019esp\u00e9r\u00e9. Certaines ont bien obtenu des am\u00e9liorations, mais seulement apr\u00e8s avoir investi des efforts consid\u00e9rables pour int\u00e9grer l\u2019IA \u00e0 leurs infrastructures existantes. Ce travail d\u2019int\u00e9gration a \u00e9t\u00e9 baptis\u00e9 \u00ab AI Scaffolding \u00bb (<em>\u00ab \u00e9chafaudages autour de l&rsquo;IA \u00bb<\/em>), soulignant son importance dans la construction d&rsquo;applications autour de l\u2019IA. En r\u00e9alit\u00e9, la d\u00e9finition d\u2019\u00ab AI scaffolding \u00bb est la m\u00eame que celle de \u00ab AI wrapper \u00bb (\u00e0 savoir, un logiciel utilisant l\u2019IA), mais avec une connotation positive.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-bluesky-social wp-block-embed-bluesky-social\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"bluesky-embed\" data-bluesky-uri=\"at:\/\/did:plc:z7oad4td5k4tfb4dttzjym7r\/app.bsky.feed.post\/3luxxboaync26\" data-bluesky-cid=\"bafyreibruybtvaeolhmx25yfrqlodchuhtbo5z4ymqa56rzdyhiypx73k4\"><p lang=\"en\">The chat interface is great for quick questions, but for real work with language models we need something more. &#34;Scaffolds&#34; &#8211; software layers that help organize our interactions &#8211; are becoming essential. Claude.ai and ChatGPT have evolved beyond chat with artifacts, knowledge bases, and memory. 1\/<\/p>&mdash; <a href=\"https:\/\/bsky.app\/profile\/did:plc:z7oad4td5k4tfb4dttzjym7r?ref_src=embed\">Dustin Moskovitz (@moskov.goodventures.org)<\/a> <a href=\"https:\/\/bsky.app\/profile\/did:plc:z7oad4td5k4tfb4dttzjym7r\/post\/3luxxboaync26?ref_src=embed\">2025-07-27T20:49:21.681Z<\/a><\/blockquote><script async src=\"https:\/\/embed.bsky.app\/static\/embed.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Il s\u2019av\u00e8re que ce travail d\u2019ing\u00e9nierie logicielle apporte bel et bien de la valeur au march\u00e9. Les valorisations des entreprises de wrappers IA le prouvent, tout comme leur base d\u2019utilisateurs en croissance. L&rsquo;\u00ab AI scaffolding \u00bb est maintenant encens\u00e9, et \u00e0 juste titre: il est indispensable pour rendre l&rsquo;IA utile.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">&quot;it&#39;s just a wrapper&quot;<br><br>tsmc is an asml wrapper valued at $1.1 trillion<br>nvidia is a tsmc wrapper valued at $3.48 trillion<br>cursor is a vs code wrapper valued at $10 billion<br>openai is an nvidia wrapper valued at $300 billion<br>perplexity is a chatgpt wrapper valued at $14 billion<\/p>&mdash; AgentSea (@tryagentsea) <a href=\"https:\/\/twitter.com\/tryagentsea\/status\/1932336953376280936?ref_src=twsrc%5Etfw\">June 10, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>En fin de compte, les \u00ab wrappers IA \u00bb et l\u2019\u00ab AI scaffolding\u00bb sont une seule et m\u00eame chose : du d\u00e9veloppement informatique normal qui utilise l\u2019IA comme un outil parmi d\u2019autres, et qui m\u00e9rite autant de respect que le d\u00e9veloppement informatique classique.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019essor des LLM (Large Language Models) d\u00e9clench\u00e9 par ChatGPT n&rsquo;a pas seulement profit\u00e9 aux grands laboratoires qui d\u00e9veloppent des mod\u00e8les [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-147","post","type-post","status-publish","format-standard","hentry","category-ia","category-llm"],"_links":{"self":[{"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/posts\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/comments?post=147"}],"version-history":[{"count":3,"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/posts\/147\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/posts\/147\/revisions\/152"}],"wp:attachment":[{"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/media?parent=147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/categories?post=147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chataignon.org\/joseph\/wp-json\/wp\/v2\/tags?post=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}